{"id":12908,"date":"2021-03-20T01:05:26","date_gmt":"2020-06-08T13:44:26","guid":{"rendered":"https:\/\/colourofstone.com\/shop\/sin%20categor\u00eda\/bianco-carrara-white-dream\/"},"modified":"2023-02-10T05:39:33","modified_gmt":"2023-02-10T05:39:33","slug":"bianco-carrara-gioia","status":"publish","type":"product","link":"https:\/\/colourofstone.com\/es\/shop\/piedra-natural\/azulejos\/bianco-carrara-gioia\/","title":{"rendered":"Bianco Carrara Gioia"},"content":{"rendered":"<p>Bianco Carrara Gioia es un m\u00e1rmol lleno de sensualidad. Su tono de base blanco cautiva con un veteado fino y gris claro. Un sue\u00f1o para varias combinaciones decorativas. Bianco Carrara Gioia se extrae en las monta\u00f1as de la ciudad de Carrara con una impresionante vista de Marina di Carrara y el mar Mediterr\u00e1neo.<\/p>\n<p>&nbsp;<\/p>\n<p>Esta piedra natural no es resistente a las heladas ni a los \u00e1cidos. Es perfectamente adecuado para interiores. Con la sensibilidad y el conocimiento adecuados, esta piedra natural tambi\u00e9n se puede utilizar en otras \u00e1reas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bianco Carrara Gioia es un m\u00e1rmol lleno de sensualidad. Su tono de base blanco cautiva con un veteado fino y gris claro. Un sue\u00f1o para varias combinaciones decorativas. Bianco Carrara Gioia se extrae en las monta\u00f1as de la ciudad de Carrara con una impresionante vista de Marina di Carrara y el mar Mediterr\u00e1neo. &nbsp; Esta <a href=\"https:\/\/colourofstone.com\/es\/shop\/piedra-natural\/azulejos\/bianco-carrara-gioia\/\" class=\"more-link\">&#8230;<\/a><\/p>\n","protected":false},"featured_media":27463,"template":"","meta":[],"product_brand":[],"product_cat":[531],"product_tag":[],"class_list":{"0":"post-12908","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-azulejos","7":"pa_farbe-blanco","8":"pa_farbe-claro","9":"pa_masseinheit-305-x-305-cm","10":"pa_masseinheit-61-x-305-cm","11":"pa_masseinheit-40-x-40-cm","12":"pa_masseinheit-457-x-457-cm","13":"pa_masseinheit-60-x-40-cm","14":"pa_masseinheit-60-x-60-cm","15":"pa_masseinheit-80-x-80-cm","16":"pa_masseinheit-100-x-100-cm","17":"pa_material-marmol","18":"pa_oberflaeche-pulido","19":"pa_oberflaeche-lijado","20":"pa_oberflaeche-cepillado","22":"first","23":"instock","24":"taxable","25":"shipping-taxable","26":"purchasable","27":"product-type-variable","28":"has-default-attributes"},"_links":{"self":[{"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/product\/12908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/media\/27463"}],"wp:attachment":[{"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/media?parent=12908"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/product_brand?post=12908"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/product_cat?post=12908"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/colourofstone.com\/es\/wp-json\/wp\/v2\/product_tag?post=12908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}